{"id":15803,"date":"2025-02-05T10:43:25","date_gmt":"2025-02-05T09:43:25","guid":{"rendered":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/"},"modified":"2025-02-05T10:43:26","modified_gmt":"2025-02-05T09:43:26","slug":"kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic","status":"publish","type":"post","link":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/","title":{"rendered":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic"},"content":{"rendered":"<div class=\"entry-content\">\n<div id=\"upx-mm-player-wrap\"><\/div>\n<div class=\"post-page\" data-page=\"1\">\n<p>Les Dallas Mavericks ont disput\u00e9 leur deuxi\u00e8me match de l&#39;\u00e8re post-luka Doncic mardi \u00e0 Philadelphie et sont tomb\u00e9s \u00e0 0-2 depuis le blockbuster choquant de samedi qui a amen\u00e9 Anthony Davis et Max Christie \u00e0 Dallas et envoy\u00e9 Doncic, Markieff Morris et Maxi Kleber \u00e0 Los Angeles et . <\/p>\n<p>La d\u00e9faite serr\u00e9e de mardi contre les Sixers a \u00e9t\u00e9 la premi\u00e8re fois que Kyrie Irving jouait, alors qu&#39;il s&#39;assit contre Cleveland, ce qui signifiait que sa disponibilit\u00e9 d&#39;apr\u00e8s-match \u00e9tait la premi\u00e8re fois que nous avons entendu parler de lui depuis le commerce de la ligue. Irving, comme tout le monde, a d\u00e9clar\u00e9 que sa premi\u00e8re r\u00e9action \u00e9tait un choc et a expliqu\u00e9 qu&#39;il \u00e9tait toujours dans le \u00abprocessus de deuil\u00bb, notant \u00e0 quel point lui et Doncic \u00e9taient devenus sur et hors du terrain (<a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/GrantAfseth\/status\/1886978754301358241\" target=\"_blank\">via Grant Afseth<\/a>).<\/p>\n<p>\u00abJuste vraiment choqu\u00e9. Vous n&#39;imaginez pas que vous allez vous pr\u00e9parer \u00e0 aller dormir et \u00e0 d\u00e9couvrir des nouvelles comme \u00e7a \u00bb, a d\u00e9clar\u00e9 Irving. \u00abAlors encore le processus de deuil en ce moment. Mon Hermano me manque. Nous avons eu beaucoup de temps ensemble &#8211; Kieff aussi et Maxi. Nous venons de construire des obligations qui allaient au-del\u00e0 du terrain de basket. Si quelqu&#39;un peut comprendre \u00e0 la maison, quand quelqu&#39;un ou quelques personnes quittent dans un m\u00e9tier, \u00e7a va \u00eatre difficile, et c&#39;est ce \u00e0 quoi nous avons affaire en ce moment. Mais c&#39;est une entreprise. C&#39;est bien au-dessus de ma note de r\u00e9mun\u00e9ration. Je dois juste s&#39;adapter et \u00eatre pr\u00eat \u00e0 accueillir dans mes nouveaux co\u00e9quipiers \u00e0 bras ouverts et \u00eatre un peu pr\u00eat \u00e0 retourner \u00e0 Dallas pour parler devant nos fans. Je sais qu&#39;ils le ressentent aussi &#8211; je le ressens aussi, les gars. C&#39;est juste une p\u00e9riode d&#39;ajustement. Je ne veux pas minimiser cela ou manquer de respect \u00e0 nos nouveaux gars, ils vont nous aider \u00e0 gagner et \u00e0 nous aider \u00e0 construire vers un championnat. Mais comme tout le monde \u00e0 la maison, le voyez un peu de loin, \u00e7a fait mal. \u00bb <\/p>\n<p>L&#39;\u00e9l\u00e9ment humain des m\u00e9tiers est toujours une chose difficile \u00e0 comprendre pleinement de l&#39;ext\u00e9rieur, mais lorsqu&#39;un commerce sort vraiment nulle part comme celui-ci, je ne peux qu&#39;imaginer la gamme sauvage des \u00e9motions que les joueurs ressentent. Irving essaie d&#39;expliquer que le mieux qu&#39;il peut, et fait un bon travail d\u00e9taillant le d\u00e9licat \u00e9quilibre des vestiaires en ce moment. Ils sont tous sous le choc de voir leur meilleur gars et un co\u00e9quipier bien-aim\u00e9 se fait \u00e9changer, et doivent traiter ces \u00e9motions tout en accueillant dans de nouveaux co\u00e9quipiers qui ont \u00e9galement trait\u00e9 avec leur propre choc et essayant de comprendre exactement comment tout cela s&#39;est pass\u00e9. <\/p>\n<p>Irving n&#39;a pas non plus h\u00e9sit\u00e9 au fait que les fans de Mavs ne sont pas satisfaits de la fa\u00e7on dont cela s&#39;est d\u00e9roul\u00e9, et il sera int\u00e9ressant de voir quelle est la r\u00e9ception pour l&#39;\u00e9quipe \u00e0 son retour \u00e0 Dallas. Le GM ne sortit pas sur le terrain, donc ce n&#39;est pas comme si les fans pourraient huer directement Nico Harrison, mais les joueurs n&#39;avaient rien \u00e0 voir avec le m\u00e9tier et sont tout aussi choqu\u00e9s que tout le monde. <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Dallas Mavericks ont disput\u00e9 leur deuxi\u00e8me match de l&#39;\u00e8re post-luka Doncic mardi \u00e0 Philadelphie et sont tomb\u00e9s \u00e0 0-2 depuis le blockbuster choquant de samedi qui a amen\u00e9 Anthony Davis et Max Christie \u00e0 Dallas et envoy\u00e9 Doncic, Markieff Morris et Maxi Kleber \u00e0 Los Angeles et . La d\u00e9faite serr\u00e9e de mardi contre &#8230; <a title=\"Kyrie Irving a d\u00e9clar\u00e9 qu&#039;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#039;&#039; apr\u00e8s le commerce soudain de Luka Doncic\" class=\"read-more\" href=\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\" aria-label=\"Plus sur Kyrie Irving a d\u00e9clar\u00e9 qu&#039;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#039;&#039; apr\u00e8s le commerce soudain de Luka Doncic\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":5771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[152,10545,52,2437,13059,4265,245,4058,4057,4264,3092,4527,13060,289],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kyrie Irving a d\u00e9clar\u00e9 qu&#039;il \u00e9tait toujours dans `` le processus de deuil &#039;&#039; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kyrie Irving a d\u00e9clar\u00e9 qu&#039;il \u00e9tait toujours dans `` le processus de deuil &#039;&#039; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me\" \/>\n<meta property=\"og:description\" content=\"Les Dallas Mavericks ont disput\u00e9 leur deuxi\u00e8me match de l&#039;\u00e8re post-luka Doncic mardi \u00e0 Philadelphie et sont tomb\u00e9s \u00e0 0-2 depuis le blockbuster choquant de samedi qui a amen\u00e9 Anthony Davis et Max Christie \u00e0 Dallas et envoy\u00e9 Doncic, Markieff Morris et Maxi Kleber \u00e0 Los Angeles et . La d\u00e9faite serr\u00e9e de mardi contre ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s - Joke Me\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-05T09:43:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T09:43:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/05\/Luka-Doncic-et-Kyrie-Irving-ont-de-nouveau-ebloui-pour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Didier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Didier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\"},\"author\":{\"name\":\"Didier\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f\"},\"headline\":\"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic\",\"datePublished\":\"2025-02-05T09:43:25+00:00\",\"dateModified\":\"2025-02-05T09:43:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\"},\"keywords\":[\"apr\u00e8s\",\"commerce\",\"dans\",\"d\u00e9clar\u00e9\",\"deuil\",\"Doncic\",\"\u00e9tait\",\"Irving\",\"Kyrie\",\"Luka\",\"processus\",\"qu39il\",\"soudain\",\"toujours\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\",\"name\":\"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans `` le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me\",\"isPartOf\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#website\"},\"datePublished\":\"2025-02-05T09:43:25+00:00\",\"dateModified\":\"2025-02-05T09:43:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.jokeme.fr\/actus\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#website\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/\",\"name\":\"Actualit\u00e9s - Joke Me\",\"description\":\"L&#039;actualit\u00e9 du rire\",\"publisher\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jokeme.fr\/actus\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\",\"name\":\"Actualit\u00e9s - Joke Me\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png\",\"contentUrl\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png\",\"width\":499,\"height\":363,\"caption\":\"Actualit\u00e9s - Joke Me\"},\"image\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f\",\"name\":\"Didier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg\",\"contentUrl\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg\",\"caption\":\"Didier\"},\"description\":\"Didier, passionn\u00e9 de cin\u00e9ma, est un r\u00e9dacteur pour le m\u00e9dia Jokeme, o\u00f9 il partage sa passion \u00e0 travers des articles divertissants et informatifs. Ayant \u00e9tudi\u00e9 le journalisme, il allie sa formation \u00e0 sa passion pour offrir un contenu de qualit\u00e9 sur le monde du cin\u00e9ma.\",\"sameAs\":[\"https:\/\/www.jokeme.fr\/actus\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans `` le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/","og_locale":"fr_FR","og_type":"article","og_title":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans `` le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me","og_description":"Les Dallas Mavericks ont disput\u00e9 leur deuxi\u00e8me match de l&#39;\u00e8re post-luka Doncic mardi \u00e0 Philadelphie et sont tomb\u00e9s \u00e0 0-2 depuis le blockbuster choquant de samedi qui a amen\u00e9 Anthony Davis et Max Christie \u00e0 Dallas et envoy\u00e9 Doncic, Markieff Morris et Maxi Kleber \u00e0 Los Angeles et . La d\u00e9faite serr\u00e9e de mardi contre ... Lire plus","og_url":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/","og_site_name":"Actualit\u00e9s - Joke Me","article_published_time":"2025-02-05T09:43:25+00:00","article_modified_time":"2025-02-05T09:43:26+00:00","og_image":[{"width":710,"height":400,"url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/05\/Luka-Doncic-et-Kyrie-Irving-ont-de-nouveau-ebloui-pour.jpg","type":"image\/jpeg"}],"author":"Didier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Didier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#article","isPartOf":{"@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/"},"author":{"name":"Didier","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f"},"headline":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic","datePublished":"2025-02-05T09:43:25+00:00","dateModified":"2025-02-05T09:43:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/"},"wordCount":583,"publisher":{"@id":"https:\/\/www.jokeme.fr\/actus\/#organization"},"keywords":["apr\u00e8s","commerce","dans","d\u00e9clar\u00e9","deuil","Doncic","\u00e9tait","Irving","Kyrie","Luka","processus","qu39il","soudain","toujours"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/","url":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/","name":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans `` le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic - Actualit\u00e9s - Joke Me","isPartOf":{"@id":"https:\/\/www.jokeme.fr\/actus\/#website"},"datePublished":"2025-02-05T09:43:25+00:00","dateModified":"2025-02-05T09:43:26+00:00","breadcrumb":{"@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jokeme.fr\/actus\/kyrie-irving-a-declare-quil-etait-toujours-dans-le-processus-de-deuil-apres-le-commerce-soudain-de-luka-doncic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jokeme.fr\/actus\/"},{"@type":"ListItem","position":2,"name":"Kyrie Irving a d\u00e9clar\u00e9 qu&#39;il \u00e9tait toujours dans \u00ab\u00a0 le processus de deuil &#39;&#39; apr\u00e8s le commerce soudain de Luka Doncic"}]},{"@type":"WebSite","@id":"https:\/\/www.jokeme.fr\/actus\/#website","url":"https:\/\/www.jokeme.fr\/actus\/","name":"Actualit\u00e9s - Joke Me","description":"L&#039;actualit\u00e9 du rire","publisher":{"@id":"https:\/\/www.jokeme.fr\/actus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jokeme.fr\/actus\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jokeme.fr\/actus\/#organization","name":"Actualit\u00e9s - Joke Me","url":"https:\/\/www.jokeme.fr\/actus\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/","url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png","contentUrl":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png","width":499,"height":363,"caption":"Actualit\u00e9s - Joke Me"},"image":{"@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f","name":"Didier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/image\/","url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg","contentUrl":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg","caption":"Didier"},"description":"Didier, passionn\u00e9 de cin\u00e9ma, est un r\u00e9dacteur pour le m\u00e9dia Jokeme, o\u00f9 il partage sa passion \u00e0 travers des articles divertissants et informatifs. Ayant \u00e9tudi\u00e9 le journalisme, il allie sa formation \u00e0 sa passion pour offrir un contenu de qualit\u00e9 sur le monde du cin\u00e9ma.","sameAs":["https:\/\/www.jokeme.fr\/actus"]}]}},"_links":{"self":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/15803"}],"collection":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/comments?post=15803"}],"version-history":[{"count":1,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/15803\/revisions"}],"predecessor-version":[{"id":15804,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/15803\/revisions\/15804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/media\/5771"}],"wp:attachment":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/media?parent=15803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/categories?post=15803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/tags?post=15803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}