{"id":25179,"date":"2026-07-15T21:42:18","date_gmt":"2026-07-15T19:42:18","guid":{"rendered":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/"},"modified":"2026-07-15T21:42:19","modified_gmt":"2026-07-15T19:42:19","slug":"les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant","status":"publish","type":"post","link":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/","title":{"rendered":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant"},"content":{"rendered":"<div class=\"eg-single-article__block-content\">\n<p id=\"par-1_83\">Les choses n&rsquo;ont pas \u00e9t\u00e9 calmes dans l&rsquo;univers de Bachelor Nation. Il y a eu pas mal de drames. Pourtant, les fans doivent encore composer avec une v\u00e9ritable s\u00e9cheresse de diffusion. Apr\u00e8s qu&rsquo;ABC a retir\u00e9 la saison de Taylor Frankie Paul de The Bachelorette de la grille en mars, le calme est revenu. Il semble que la saison 30 de The Bachelor soit sur le point d\u2019arriver. Bien que le r\u00e9seau ne livre pas beaucoup d\u2019indices sur ce qui va arriver, les d\u00e9tectives du net se disent confiants de savoir qui sera le prochain protagoniste gr\u00e2ce \u00e0 un changement dans le planning de tournage.<\/p>\n<h2 class=\"wp-block-heading\" id=\"h-a-casting-form-hints-at-a-late-filming-start-for-season-30-of-the-bachelor\">Un formulaire de casting laisse entrevoir un d\u00e9marrage tardif du tournage pour la saison 30 de \u00ab The Bachelor \u00bb<\/h2>\n<p id=\"par-2_63\">Des fans attentifs scrutant la candidature officielle pour The Bachelor, saison 30, ont rep\u00e9r\u00e9 quelque chose d&rsquo;\u00e9trange enfoui dans les documents. L&rsquo;une des consignes demande aux candidat\u00b7e\u00b7s de pr\u00e9ciser leurs disponibilit\u00e9s et tout conflit d&#8217;emploi pour une fen\u00eatre de production pr\u00e9cise. Cette fen\u00eatre semble avoir une signification importante. Elle sugg\u00e8re que le tournage se d\u00e9roulera de janvier \u00e0 mars 2027, bien plus tard que le tournage d&rsquo;automne habituel de la franchise.<\/p>\n<p id=\"par-3_71\">G\u00e9n\u00e9ralement, le r\u00e9seau annonce le nouveau\/la nouvelle protagoniste en fin d&rsquo;\u00e9t\u00e9 ou au d\u00e9but de l&rsquo;automne; le tournage se d\u00e9roule de septembre \u00e0 novembre, et la saison est diffus\u00e9e pour la premi\u00e8re fois en janvier de l&rsquo;ann\u00e9e suivante. La saison 30 \u00e9tait cens\u00e9e suivre ce sch\u00e9ma apr\u00e8s qu\u2019ABC ait confirm\u00e9 le renouvellement du programme l&rsquo;\u00e9t\u00e9 dernier. Au lieu de cela, le document de casting sugg\u00e8re un retard de plusieurs mois. Les d\u00e9tectives en ligne pensent que ce retard est directement li\u00e9 \u00e0 la personne qui rejoindra la saison marquante en tant que protagoniste.<\/p>\n<h2 class=\"wp-block-heading\" id=\"h-everyone-thinks-the-delay-is-connected-to-taylor-frankie-paul-s-scrapped-season\">Tout le monde pense que le retard est li\u00e9 \u00e0 la saison abandonn\u00e9e de Taylor Frankie Paul<\/h2>\n<p id=\"par-4_97\">ABC semblait confiant dans son plan jusqu\u2019\u00e0 ce que le drame juridique entourant Taylor Frankie Paul menace de bouleverser toute la franchise. Le calendrier de tournage repouss\u00e9 pourrait \u00eatre li\u00e9 au sort de la saison de The Bachelorette de Taylor Frankie Paul qui a \u00e9t\u00e9 mise de c\u00f4t\u00e9. La rumeur veut que le r\u00e9seau finira par diffuser la saison de Paul, possiblement d\u00e8s cet \u00e9t\u00e9. Cette diffusion retard\u00e9e pourrait expliquer le d\u00e9calage du tournage. Les passionn\u00e9s de Bachelor Nation soutiennent que le r\u00e9seau voudrait laisser aux fans le temps de faire connaissance avec le\/la candidat(e) retenu(e), qu\u2019ils estiment li\u00e9 \u00e0 la saison retard\u00e9e de The Bachelorette de Taylor Frankie Paul.<\/p>\n<p id=\"par-5_53\">Les discussions sur le planning ont aussi raviv\u00e9 les sp\u00e9culations autour de Shane Parton, l\u2019un des candidats de la saison non diffus\u00e9e de Paul, en tant que favori pour devenir le prochain lead de The Bachelor. Les fans soutiennent que si la franchise d\u00e9tient d\u00e9j\u00e0 des images in\u00e9dits de Parton, le promouvoir au r\u00f4le principal aurait du sens, tant sur le plan narratif que financier.<\/p>\n<h2 class=\"wp-block-heading\" id=\"h-right-now-the-production-team-isn-t-talking\">Pour l\u2019instant, l\u2019\u00e9quipe de production reste silencieuse<\/h2>\n<p id=\"par-6_45\">Les producteurs n&rsquo;ont pas confirm\u00e9 qui sera le\/la protagoniste, une date de d\u00e9but du tournage, ni les plans pour la saison mise en attente de Paul. Le patron de The Bachelor, Jonathan Prince, a d\u00e9clar\u00e9 \u00e0 Variety plus t\u00f4t cette ann\u00e9e qu&rsquo;aucune d\u00e9cision concernant le prochain Bachelor n&rsquo;avait \u00e9t\u00e9 prise, ajoutant que la franchise n&rsquo;avait pas besoin d&rsquo;acc\u00e9l\u00e9rer l&rsquo;annonce.<\/p>\n<p id=\"par-7_20\">Jusqu&rsquo;\u00e0 ce qu&rsquo;ABC fasse une annonce officielle, le dossier d&rsquo;internet repose enti\u00e8rement sur des preuves circonstancielles. Pourtant, ce sont des preuves convaincantes.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les choses n&rsquo;ont pas \u00e9t\u00e9 calmes dans l&rsquo;univers de Bachelor Nation. Il y a eu pas mal de drames. Pourtant, les fans doivent encore composer avec une v\u00e9ritable s\u00e9cheresse de diffusion. Apr\u00e8s qu&rsquo;ABC a retir\u00e9 la saison de Taylor Frankie Paul de The Bachelorette de la grille en mars, le calme est revenu. Il semble &#8230; <a title=\"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant\" class=\"read-more\" href=\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\" aria-label=\"Plus sur Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":25180,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[17004,124,66,981,17132,3357,3579,651,2226],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me\" \/>\n<meta property=\"og:description\" content=\"Les choses n&rsquo;ont pas \u00e9t\u00e9 calmes dans l&rsquo;univers de Bachelor Nation. Il y a eu pas mal de drames. Pourtant, les fans doivent encore composer avec une v\u00e9ritable s\u00e9cheresse de diffusion. Apr\u00e8s qu&rsquo;ABC a retir\u00e9 la saison de Taylor Frankie Paul de The Bachelorette de la grille en mars, le calme est revenu. Il semble ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s - Joke Me\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T19:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T19:42:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2026\/07\/1784144538.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Didier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Didier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\"},\"author\":{\"name\":\"Didier\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f\"},\"headline\":\"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant\",\"datePublished\":\"2026-07-15T19:42:18+00:00\",\"dateModified\":\"2026-07-15T19:42:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\"},\"wordCount\":640,\"publisher\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\"},\"keywords\":[\"Bachelor\",\"fans\",\"les\",\"pensent\",\"planning\",\"pr\u00e9tendant\",\"prochain\",\"r\u00e9v\u00e8le\",\"tournage\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\",\"name\":\"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me\",\"isPartOf\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#website\"},\"datePublished\":\"2026-07-15T19:42:18+00:00\",\"dateModified\":\"2026-07-15T19:42:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.jokeme.fr\/actus\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#website\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/\",\"name\":\"Actualit\u00e9s - Joke Me\",\"description\":\"L&#039;actualit\u00e9 du rire\",\"publisher\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jokeme.fr\/actus\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#organization\",\"name\":\"Actualit\u00e9s - Joke Me\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png\",\"contentUrl\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png\",\"width\":499,\"height\":363,\"caption\":\"Actualit\u00e9s - Joke Me\"},\"image\":{\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f\",\"name\":\"Didier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg\",\"contentUrl\":\"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg\",\"caption\":\"Didier\"},\"description\":\"Didier, passionn\u00e9 de cin\u00e9ma, est un r\u00e9dacteur pour le m\u00e9dia Jokeme, o\u00f9 il partage sa passion \u00e0 travers des articles divertissants et informatifs. Ayant \u00e9tudi\u00e9 le journalisme, il allie sa formation \u00e0 sa passion pour offrir un contenu de qualit\u00e9 sur le monde du cin\u00e9ma.\",\"sameAs\":[\"https:\/\/www.jokeme.fr\/actus\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/","og_locale":"fr_FR","og_type":"article","og_title":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me","og_description":"Les choses n&rsquo;ont pas \u00e9t\u00e9 calmes dans l&rsquo;univers de Bachelor Nation. Il y a eu pas mal de drames. Pourtant, les fans doivent encore composer avec une v\u00e9ritable s\u00e9cheresse de diffusion. Apr\u00e8s qu&rsquo;ABC a retir\u00e9 la saison de Taylor Frankie Paul de The Bachelorette de la grille en mars, le calme est revenu. Il semble ... Lire plus","og_url":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/","og_site_name":"Actualit\u00e9s - Joke Me","article_published_time":"2026-07-15T19:42:18+00:00","article_modified_time":"2026-07-15T19:42:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2026\/07\/1784144538.webp","type":"image\/webp"}],"author":"Didier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Didier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#article","isPartOf":{"@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/"},"author":{"name":"Didier","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f"},"headline":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant","datePublished":"2026-07-15T19:42:18+00:00","dateModified":"2026-07-15T19:42:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/"},"wordCount":640,"publisher":{"@id":"https:\/\/www.jokeme.fr\/actus\/#organization"},"keywords":["Bachelor","fans","les","pensent","planning","pr\u00e9tendant","prochain","r\u00e9v\u00e8le","tournage"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/","url":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/","name":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant - Actualit\u00e9s - Joke Me","isPartOf":{"@id":"https:\/\/www.jokeme.fr\/actus\/#website"},"datePublished":"2026-07-15T19:42:18+00:00","dateModified":"2026-07-15T19:42:19+00:00","breadcrumb":{"@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jokeme.fr\/actus\/les-fans-de-the-bachelor-pensent-que-le-planning-de-tournage-revele-le-prochain-pretendant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jokeme.fr\/actus\/"},{"@type":"ListItem","position":2,"name":"Les fans de The Bachelor pensent que le planning de tournage r\u00e9v\u00e8le le prochain pr\u00e9tendant"}]},{"@type":"WebSite","@id":"https:\/\/www.jokeme.fr\/actus\/#website","url":"https:\/\/www.jokeme.fr\/actus\/","name":"Actualit\u00e9s - Joke Me","description":"L&#039;actualit\u00e9 du rire","publisher":{"@id":"https:\/\/www.jokeme.fr\/actus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jokeme.fr\/actus\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jokeme.fr\/actus\/#organization","name":"Actualit\u00e9s - Joke Me","url":"https:\/\/www.jokeme.fr\/actus\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/","url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png","contentUrl":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2023\/06\/cropped-Logo-Joke-Me.png","width":499,"height":363,"caption":"Actualit\u00e9s - Joke Me"},"image":{"@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/f0c6ad0d33ca144389e81e45a212928f","name":"Didier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jokeme.fr\/actus\/#\/schema\/person\/image\/","url":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg","contentUrl":"https:\/\/www.jokeme.fr\/actus\/wp-content\/uploads\/2024\/03\/jokeme-didier.jpg","caption":"Didier"},"description":"Didier, passionn\u00e9 de cin\u00e9ma, est un r\u00e9dacteur pour le m\u00e9dia Jokeme, o\u00f9 il partage sa passion \u00e0 travers des articles divertissants et informatifs. Ayant \u00e9tudi\u00e9 le journalisme, il allie sa formation \u00e0 sa passion pour offrir un contenu de qualit\u00e9 sur le monde du cin\u00e9ma.","sameAs":["https:\/\/www.jokeme.fr\/actus"]}]}},"_links":{"self":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/25179"}],"collection":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/comments?post=25179"}],"version-history":[{"count":1,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/25179\/revisions"}],"predecessor-version":[{"id":25181,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/posts\/25179\/revisions\/25181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/media\/25180"}],"wp:attachment":[{"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/media?parent=25179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/categories?post=25179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jokeme.fr\/actus\/wp-json\/wp\/v2\/tags?post=25179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}